{"id":3546,"date":"2023-10-10T10:10:09","date_gmt":"2023-10-10T08:10:09","guid":{"rendered":"https:\/\/montreuilsloir.fr\/?p=3546"},"modified":"2023-10-10T10:10:10","modified_gmt":"2023-10-10T08:10:10","slug":"travaux-rd-74","status":"publish","type":"post","link":"https:\/\/montreuilsloir.fr\/index.php\/2023\/10\/10\/travaux-rd-74\/","title":{"rendered":"TRAVAUX RD 74"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>Du 23 octobre au 27 octobre 2023, la RD 74 sera COMPLETEMENT ferm\u00e9e !!! (ci joint le plan)<br>Un rabotage de la chauss\u00e9e, une pose de la grave bitume et un enrob\u00e9 sur les trottoirs sera r\u00e9alis\u00e9.<br><br>Le 30 et 31 octobre 2023, le RD sera de nouveau COMPLETEMENT ferm\u00e9e pour la r\u00e9alisation des enrob\u00e9s sur toute la travers\u00e9e du bourg.<br><br>ATTENTION RIVRAINS HABITANTS LE LONG DE LA RD74 :<br>Merci de bien vouloir stationner en dehors de la zone de travaux durant cette p\u00e9riode.\u00a0\u00bb<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/montreuilsloir.fr\/wp-content\/uploads\/2023\/10\/10102023Scan-.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 10102023Scan.\"><\/object><a id=\"wp-block-file--media-6e913f5a-128b-40ff-8cb4-2f31da377536\" href=\"https:\/\/montreuilsloir.fr\/wp-content\/uploads\/2023\/10\/10102023Scan-.pdf\">10102023Scan<\/a><a href=\"https:\/\/montreuilsloir.fr\/wp-content\/uploads\/2023\/10\/10102023Scan-.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-6e913f5a-128b-40ff-8cb4-2f31da377536\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-b030f2fd-df33-473a-9307-ef1ab6c62696\" href=\"https:\/\/montreuilsloir.fr\/wp-content\/uploads\/2023\/10\/travaux-rd.jpg\">travaux rd<\/a><a href=\"https:\/\/montreuilsloir.fr\/wp-content\/uploads\/2023\/10\/travaux-rd.jpg\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-b030f2fd-df33-473a-9307-ef1ab6c62696\">T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Du 23 octobre au 27 octobre 2023, la RD 74 sera COMPLETEMENT ferm\u00e9e !!! (ci joint le plan)Un rabotage de la chauss\u00e9e, une pose de la grave bitume et un <a class=\"more-link\" href=\"https:\/\/montreuilsloir.fr\/index.php\/2023\/10\/10\/travaux-rd-74\/\">Lire plus &#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-3546","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/3546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3546"}],"version-history":[{"count":1,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/3546\/revisions"}],"predecessor-version":[{"id":3547,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/3546\/revisions\/3547"}],"wp:attachment":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}