{"id":2288,"date":"2021-09-09T19:59:16","date_gmt":"2021-09-09T17:59:16","guid":{"rendered":"https:\/\/montreuilsloir.fr\/?p=2288"},"modified":"2021-09-09T19:59:17","modified_gmt":"2021-09-09T17:59:17","slug":"association-entraide-informatique","status":"publish","type":"post","link":"https:\/\/montreuilsloir.fr\/index.php\/2021\/09\/09\/association-entraide-informatique\/","title":{"rendered":"Association Entraide informatique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pour la reprise de ses activit\u00e9s, l&rsquo;association Entraide\u00a0informatique vous informe qu&rsquo;une r\u00e9union d&rsquo;information et de pr\u00e9sentation aura lieu le\u00a0JEUDI 16 SEPTEMBRE 2021 \u00e0 18 H\u00a0\u00a0\u00e0 la salle communale de Montreuil sur Loir<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Comptant sur\u00a0votre pr\u00e9sence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fran\u00e7oise Brillaud 06 15 94 82 14<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la reprise de ses activit\u00e9s, l&rsquo;association Entraide\u00a0informatique vous informe qu&rsquo;une r\u00e9union d&rsquo;information et de pr\u00e9sentation aura lieu le\u00a0JEUDI 16 SEPTEMBRE 2021 \u00e0 18 H\u00a0\u00a0\u00e0 la salle communale de Montreuil <a class=\"more-link\" href=\"https:\/\/montreuilsloir.fr\/index.php\/2021\/09\/09\/association-entraide-informatique\/\">Lire plus &#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2288","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/2288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2288"}],"version-history":[{"count":1,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/2288\/revisions"}],"predecessor-version":[{"id":2289,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/2288\/revisions\/2289"}],"wp:attachment":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}