{"id":2282,"date":"2021-09-03T18:24:08","date_gmt":"2021-09-03T16:24:08","guid":{"rendered":"https:\/\/montreuilsloir.fr\/?p=2282"},"modified":"2021-09-03T18:24:09","modified_gmt":"2021-09-03T16:24:09","slug":"la-bibliotheque-recrute-des-benevoles","status":"publish","type":"post","link":"https:\/\/montreuilsloir.fr\/index.php\/2021\/09\/03\/la-bibliotheque-recrute-des-benevoles\/","title":{"rendered":"La biblioth\u00e8que recrute des b\u00e9n\u00e9voles !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si vous avez un peu de temps, le go\u00fbt des livres et des \u00e9changes, venez rejoindre l&rsquo;\u00e9quipe des b\u00e9n\u00e9voles de la biblioth\u00e8que !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prochaine r\u00e9union des b\u00e9n\u00e9voles est pr\u00e9vue le mercredi 22 septembre \u00e0 19h30, salle communale. Vous y serez les bienvenus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous avez un peu de temps, le go\u00fbt des livres et des \u00e9changes, venez rejoindre l&rsquo;\u00e9quipe des b\u00e9n\u00e9voles de la biblioth\u00e8que ! La prochaine r\u00e9union des b\u00e9n\u00e9voles est pr\u00e9vue <a class=\"more-link\" href=\"https:\/\/montreuilsloir.fr\/index.php\/2021\/09\/03\/la-bibliotheque-recrute-des-benevoles\/\">Lire plus &#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2282","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/2282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2282"}],"version-history":[{"count":1,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/2282\/revisions"}],"predecessor-version":[{"id":2283,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/posts\/2282\/revisions\/2283"}],"wp:attachment":[{"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montreuilsloir.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}